{"id":2812,"date":"2023-06-20T18:03:03","date_gmt":"2023-06-20T23:03:03","guid":{"rendered":"https:\/\/foriu.mx\/?post_type=servicios&#038;p=2812"},"modified":"2026-07-09T09:12:47","modified_gmt":"2026-07-09T14:12:47","slug":"dos-peinado-maquillaje-premium","status":"publish","type":"servicios","link":"https:\/\/foriu.com\/co\/servicios\/dos-peinado-maquillaje-premium\/","title":{"rendered":"x2 Peinado + x2 Maquillaje Premium"},"content":{"rendered":"","protected":false},"featured_media":9743,"template":"","ubicacion_de_los_servicios":[8,9,318,317,322,319,323,324,325,326],"tipo_de_servicio":[60],"se-puede-reservar":[252],"class_list":["post-2812","servicios","type-servicios","status-publish","has-post-thumbnail","hentry","ubicacion_de_los_servicios-bogota","ubicacion_de_los_servicios-medellin","ubicacion_de_los_servicios-cartagena","ubicacion_de_los_servicios-cali","ubicacion_de_los_servicios-barranquilla","ubicacion_de_los_servicios-santa-marta","ubicacion_de_los_servicios-bucaramanga","ubicacion_de_los_servicios-pereira","ubicacion_de_los_servicios-armenia","ubicacion_de_los_servicios-manizales","tipo_de_servicio-social-premium","se-puede-reservar-no"],"acf":[],"_links":{"self":[{"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/servicios\/2812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/servicios"}],"about":[{"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/types\/servicios"}],"version-history":[{"count":17,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/servicios\/2812\/revisions"}],"predecessor-version":[{"id":9487,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/servicios\/2812\/revisions\/9487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/media\/9743"}],"wp:attachment":[{"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/media?parent=2812"}],"wp:term":[{"taxonomy":"ubicacion_de_los_servicios","embeddable":true,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/ubicacion_de_los_servicios?post=2812"},{"taxonomy":"tipo_de_servicio","embeddable":true,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/tipo_de_servicio?post=2812"},{"taxonomy":"se-puede-reservar","embeddable":true,"href":"https:\/\/foriu.com\/co\/wp-json\/wp\/v2\/se-puede-reservar?post=2812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}